{"id":18264,"date":"2023-12-27T12:49:00","date_gmt":"2023-12-27T17:49:00","guid":{"rendered":"https:\/\/ccli.ubc.ca\/?post_type=resource&#038;p=18264"},"modified":"2024-02-27T12:51:51","modified_gmt":"2024-02-27T17:51:51","slug":"nature-and-social-aspects-of-climate-related-risks-and-opportunities","status":"publish","type":"resource","link":"https:\/\/ccli.ubc.ca\/fr\/resource\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\/","title":{"rendered":"Nature and social aspects of climate-related risks and opportunities"},"content":{"rendered":"\n<p>La norme IFRS S2 exige d\u2019une entit\u00e9 qu\u2019elle divulgue des informations sur ses risques et opportunit\u00e9s li\u00e9s au climat. Les entit\u00e9s peuvent identifier les risques et les opportunit\u00e9s li\u00e9s au climat \u00e0 la jonction du climat et de la nature (par exemple, ceux li\u00e9s \u00e0 l\u2019eau et \u00e0 la d\u00e9forestation), ainsi que ceux qui sont \u00e9troitement associ\u00e9s aux aspects socio-\u00e9conomiques, tels que la transition juste vers une \u00e9conomie sobre en carbone. Les parties prenantes ont demand\u00e9 si \u2013 et le cas \u00e9ch\u00e9ant, comment \u2013 les entit\u00e9s devraient prendre en compte ces \u00ab aspects naturels et sociaux \u00bb des risques et opportunit\u00e9s li\u00e9s au climat lorsqu\u2019elles appliquent les exigences de l\u2019IFRS S2 pour pr\u00e9parer leurs divulgations li\u00e9es au climat.<\/p>\n\n\n\n<p>Ce mat\u00e9riel p\u00e9dagogique, qui comprend trois exemples, explique et illustre la mani\u00e8re dont les entit\u00e9s pourraient appliquer les exigences de l\u2019IFRS S2 et S1 dans de telles circonstances afin de fournir des informations mat\u00e9rielles aux utilisateurs des rapports financiers \u00e0 usage g\u00e9n\u00e9ral. Les exemples se concentrent sur des exigences particuli\u00e8res et n\u2019ont donc pas pour but d\u2019expliquer ou d\u2019illustrer comment un entit\u00e9 appliquerait toutes les exigences fondamentales des normes IFRS S2 et S1, m\u00eame dans la mesure o\u00f9 elles sont li\u00e9es aux risques et opportunit\u00e9s discut\u00e9s.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.ifrs.org\/content\/dam\/ifrs\/supporting-implementation\/ifrs-s2\/issb-naturesocialaspectsofclimate-relatedrisks-dec2023.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">T\u00c9L\u00c9CHARGER<\/a><\/div>\n<\/div>\n\n\n\n<p><em>*Cette ressource est en anglais.<\/em><\/p>\n","protected":false},"featured_media":18256,"template":"","resource_type":[73,28],"topic":[113],"area":[115],"class_list":["post-18264","resource","type-resource","status-publish","has-post-thumbnail","hentry","topic-risques-opportunites-climatiques","area-international-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nature and social aspects of climate-related risks and opportunities - Canada Climate Law Initiative<\/title>\n<meta name=\"description\" content=\"Ce mat\u00e9riel p\u00e9dagogique, qui comprend trois exemples, explique et illustre la mani\u00e8re dont les entit\u00e9s pourraient appliquer les exigences de l\u2019IFRS S2 et S1 dans de telles circonstances afin de fournir des informations mat\u00e9rielles aux utilisateurs des rapports financiers \u00e0 usage g\u00e9n\u00e9ral. Les exemples se concentrent sur des exigences particuli\u00e8res et n\u2019ont donc pas pour but d\u2019expliquer ou d\u2019illustrer comment un entit\u00e9 appliquerait toutes les exigences fondamentales des normes IFRS S2 et S1, m\u00eame dans la mesure o\u00f9 elles sont li\u00e9es aux risques et opportunit\u00e9s discut\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccli.ubc.ca\/fr\/resource\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nature and social aspects of climate-related risks and opportunities\" \/>\n<meta property=\"og:description\" content=\"Ce mat\u00e9riel p\u00e9dagogique, qui comprend trois exemples, explique et illustre la mani\u00e8re dont les entit\u00e9s pourraient appliquer les exigences de l\u2019IFRS S2 et S1 dans de telles circonstances afin de fournir des informations mat\u00e9rielles aux utilisateurs des rapports financiers \u00e0 usage g\u00e9n\u00e9ral. Les exemples se concentrent sur des exigences particuli\u00e8res et n\u2019ont donc pas pour but d\u2019expliquer ou d\u2019illustrer comment un entit\u00e9 appliquerait toutes les exigences fondamentales des normes IFRS S2 et S1, m\u00eame dans la mesure o\u00f9 elles sont li\u00e9es aux risques et opportunit\u00e9s discut\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccli.ubc.ca\/fr\/resource\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\/\" \/>\n<meta property=\"og:site_name\" content=\"Canada Climate Law Initiative\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-27T17:51:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccli.ubc.ca\/wp-content\/uploads\/2024\/02\/2h-media-Cked1I22aag-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Nature and social aspects of climate-related risks and opportunities\" \/>\n<meta name=\"twitter:description\" content=\"Ce mat\u00e9riel p\u00e9dagogique, qui comprend trois exemples, explique et illustre la mani\u00e8re dont les entit\u00e9s pourraient appliquer les exigences de l\u2019IFRS S2 et S1 dans de telles circonstances afin de fournir des informations mat\u00e9rielles aux utilisateurs des rapports financiers \u00e0 usage g\u00e9n\u00e9ral. Les exemples se concentrent sur des exigences particuli\u00e8res et n\u2019ont donc pas pour but d\u2019expliquer ou d\u2019illustrer comment un entit\u00e9 appliquerait toutes les exigences fondamentales des normes IFRS S2 et S1, m\u00eame dans la mesure o\u00f9 elles sont li\u00e9es aux risques et opportunit\u00e9s discut\u00e9s.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/ccli.ubc.ca\/wp-content\/uploads\/2024\/02\/2h-media-Cked1I22aag-unsplash-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccli.ubc.ca\\\/fr\\\/resource\\\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\\\/\",\"url\":\"https:\\\/\\\/ccli.ubc.ca\\\/fr\\\/resource\\\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\\\/\",\"name\":\"Nature and social aspects of climate-related risks and opportunities - Canada Climate Law Initiative\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccli.ubc.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ccli.ubc.ca\\\/fr\\\/resource\\\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ccli.ubc.ca\\\/fr\\\/resource\\\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccli.ubc.ca\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/2h-media-Cked1I22aag-unsplash-scaled.jpg\",\"datePublished\":\"2023-12-27T17:49:00+00:00\",\"dateModified\":\"2024-02-27T17:51:51+00:00\",\"description\":\"Ce mat\u00e9riel p\u00e9dagogique, qui comprend trois exemples, explique et illustre la mani\u00e8re dont les entit\u00e9s pourraient appliquer les exigences de l\u2019IFRS S2 et S1 dans de telles circonstances afin de fournir des informations mat\u00e9rielles aux utilisateurs des rapports financiers \u00e0 usage g\u00e9n\u00e9ral. Les exemples se concentrent sur des exigences particuli\u00e8res et n\u2019ont donc pas pour but d\u2019expliquer ou d\u2019illustrer comment un entit\u00e9 appliquerait toutes les exigences fondamentales des normes IFRS S2 et S1, m\u00eame dans la mesure o\u00f9 elles sont li\u00e9es aux risques et opportunit\u00e9s discut\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccli.ubc.ca\\\/fr\\\/resource\\\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccli.ubc.ca\\\/fr\\\/resource\\\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ccli.ubc.ca\\\/fr\\\/resource\\\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ccli.ubc.ca\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/2h-media-Cked1I22aag-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/ccli.ubc.ca\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/2h-media-Cked1I22aag-unsplash-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccli.ubc.ca\\\/fr\\\/resource\\\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ccli.ubc.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nature and social aspects of climate-related risks and opportunities\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccli.ubc.ca\\\/#website\",\"url\":\"https:\\\/\\\/ccli.ubc.ca\\\/\",\"name\":\"Canada Climate Law Initiative\",\"description\":\"Understand climate-related risks and opportunities\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccli.ubc.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nature and social aspects of climate-related risks and opportunities - Canada Climate Law Initiative","description":"Ce mat\u00e9riel p\u00e9dagogique, qui comprend trois exemples, explique et illustre la mani\u00e8re dont les entit\u00e9s pourraient appliquer les exigences de l\u2019IFRS S2 et S1 dans de telles circonstances afin de fournir des informations mat\u00e9rielles aux utilisateurs des rapports financiers \u00e0 usage g\u00e9n\u00e9ral. Les exemples se concentrent sur des exigences particuli\u00e8res et n\u2019ont donc pas pour but d\u2019expliquer ou d\u2019illustrer comment un entit\u00e9 appliquerait toutes les exigences fondamentales des normes IFRS S2 et S1, m\u00eame dans la mesure o\u00f9 elles sont li\u00e9es aux risques et opportunit\u00e9s discut\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccli.ubc.ca\/fr\/resource\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\/","og_locale":"fr_FR","og_type":"article","og_title":"Nature and social aspects of climate-related risks and opportunities","og_description":"Ce mat\u00e9riel p\u00e9dagogique, qui comprend trois exemples, explique et illustre la mani\u00e8re dont les entit\u00e9s pourraient appliquer les exigences de l\u2019IFRS S2 et S1 dans de telles circonstances afin de fournir des informations mat\u00e9rielles aux utilisateurs des rapports financiers \u00e0 usage g\u00e9n\u00e9ral. Les exemples se concentrent sur des exigences particuli\u00e8res et n\u2019ont donc pas pour but d\u2019expliquer ou d\u2019illustrer comment un entit\u00e9 appliquerait toutes les exigences fondamentales des normes IFRS S2 et S1, m\u00eame dans la mesure o\u00f9 elles sont li\u00e9es aux risques et opportunit\u00e9s discut\u00e9s.","og_url":"https:\/\/ccli.ubc.ca\/fr\/resource\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\/","og_site_name":"Canada Climate Law Initiative","article_modified_time":"2024-02-27T17:51:51+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/ccli.ubc.ca\/wp-content\/uploads\/2024\/02\/2h-media-Cked1I22aag-unsplash-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Nature and social aspects of climate-related risks and opportunities","twitter_description":"Ce mat\u00e9riel p\u00e9dagogique, qui comprend trois exemples, explique et illustre la mani\u00e8re dont les entit\u00e9s pourraient appliquer les exigences de l\u2019IFRS S2 et S1 dans de telles circonstances afin de fournir des informations mat\u00e9rielles aux utilisateurs des rapports financiers \u00e0 usage g\u00e9n\u00e9ral. Les exemples se concentrent sur des exigences particuli\u00e8res et n\u2019ont donc pas pour but d\u2019expliquer ou d\u2019illustrer comment un entit\u00e9 appliquerait toutes les exigences fondamentales des normes IFRS S2 et S1, m\u00eame dans la mesure o\u00f9 elles sont li\u00e9es aux risques et opportunit\u00e9s discut\u00e9s.","twitter_image":"https:\/\/ccli.ubc.ca\/wp-content\/uploads\/2024\/02\/2h-media-Cked1I22aag-unsplash-scaled.jpg","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ccli.ubc.ca\/fr\/resource\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\/","url":"https:\/\/ccli.ubc.ca\/fr\/resource\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\/","name":"Nature and social aspects of climate-related risks and opportunities - Canada Climate Law Initiative","isPartOf":{"@id":"https:\/\/ccli.ubc.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccli.ubc.ca\/fr\/resource\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\/#primaryimage"},"image":{"@id":"https:\/\/ccli.ubc.ca\/fr\/resource\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\/#primaryimage"},"thumbnailUrl":"https:\/\/ccli.ubc.ca\/wp-content\/uploads\/2024\/02\/2h-media-Cked1I22aag-unsplash-scaled.jpg","datePublished":"2023-12-27T17:49:00+00:00","dateModified":"2024-02-27T17:51:51+00:00","description":"Ce mat\u00e9riel p\u00e9dagogique, qui comprend trois exemples, explique et illustre la mani\u00e8re dont les entit\u00e9s pourraient appliquer les exigences de l\u2019IFRS S2 et S1 dans de telles circonstances afin de fournir des informations mat\u00e9rielles aux utilisateurs des rapports financiers \u00e0 usage g\u00e9n\u00e9ral. Les exemples se concentrent sur des exigences particuli\u00e8res et n\u2019ont donc pas pour but d\u2019expliquer ou d\u2019illustrer comment un entit\u00e9 appliquerait toutes les exigences fondamentales des normes IFRS S2 et S1, m\u00eame dans la mesure o\u00f9 elles sont li\u00e9es aux risques et opportunit\u00e9s discut\u00e9s.","breadcrumb":{"@id":"https:\/\/ccli.ubc.ca\/fr\/resource\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccli.ubc.ca\/fr\/resource\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ccli.ubc.ca\/fr\/resource\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\/#primaryimage","url":"https:\/\/ccli.ubc.ca\/wp-content\/uploads\/2024\/02\/2h-media-Cked1I22aag-unsplash-scaled.jpg","contentUrl":"https:\/\/ccli.ubc.ca\/wp-content\/uploads\/2024\/02\/2h-media-Cked1I22aag-unsplash-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/ccli.ubc.ca\/fr\/resource\/nature-and-social-aspects-of-climate-related-risks-and-opportunities\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ccli.ubc.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Nature and social aspects of climate-related risks and opportunities"}]},{"@type":"WebSite","@id":"https:\/\/ccli.ubc.ca\/#website","url":"https:\/\/ccli.ubc.ca\/","name":"Canada Climate Law Initiative","description":"Understand climate-related risks and opportunities","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccli.ubc.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/resource\/18264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/types\/resource"}],"version-history":[{"count":1,"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/resource\/18264\/revisions"}],"predecessor-version":[{"id":18266,"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/resource\/18264\/revisions\/18266"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/media\/18256"}],"wp:attachment":[{"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/media?parent=18264"}],"wp:term":[{"taxonomy":"resource_type","embeddable":true,"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/resource_type?post=18264"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/topic?post=18264"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/area?post=18264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}