{"id":4880,"date":"2017-10-01T17:02:00","date_gmt":"2017-10-01T21:02:00","guid":{"rendered":"http:\/\/ccli.machinedev.ca\/resource\/faqs-statement-of-investment-policies-and-procedures-sipp\/"},"modified":"2021-11-02T15:15:17","modified_gmt":"2021-11-02T19:15:17","slug":"faqs-statement-of-investment-policies-and-procedures-sipp","status":"publish","type":"resource","link":"https:\/\/ccli.ubc.ca\/fr\/resource\/faqs-statement-of-investment-policies-and-procedures-sipp\/","title":{"rendered":"FAQ concernant l&rsquo;\u00c9nonc\u00e9 des politiques et des proc\u00e9dures de placement (EPPP)"},"content":{"rendered":"\n<p>L&rsquo;\u00e9nonc\u00e9 des politiques et des proc\u00e9dures est un document qui contient des renseignements sur les politiques et proc\u00e9dures de placement concernant le portefeuille de placements et les pr\u00eats d&rsquo;un r\u00e9gime. En vertu du paragraphe 78 (1) du R\u00e8glement, l&rsquo;administrateur d&rsquo;un r\u00e9gime de retraite doit \u00e9tablir pour le r\u00e9gime un \u00e9nonc\u00e9 des politiques et des proc\u00e9dures de placement qui satisfait aux exigences du r\u00e8glement f\u00e9d\u00e9ral sur les placements tel qu\u2019il est adapt\u00e9 aux articles 47.8 et 79 du R\u00e8glement.&nbsp;\u00c0 partir du 1er janvier 2016, les administrateurs de r\u00e9gimes de retraite enregistr\u00e9s en Ontario doivent d\u00e9poser leur EPPP ainsi que des modifications \u00e0 l&rsquo;EPPP aupr\u00e8s de la CSFO.&nbsp;<\/p>\n\n\n\n<p>Les questions et r\u00e9ponses suivantes donnent des renseignements.&nbsp;Depuis le&nbsp; f\u00e9vrier 2016, la FAQ a \u00e9t\u00e9 renum\u00e9rot\u00e9e afin de simplifier le contenu. Chaque question de la FAQ montre la date de publication.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background no-border-radius\" href=\"http:\/\/www.fsco.gov.on.ca\/fr\/pensions\/legislative\/pages\/sipp.aspx\" style=\"background-color:#2e5b66\" target=\"_blank\" rel=\"noreferrer noopener\">Lisez le FAQ<\/a><\/div>\n<\/div>\n","protected":false},"featured_media":2037,"template":"","resource_type":[72],"topic":[102],"area":[105],"class_list":["post-4880","resource","type-resource","status-publish","has-post-thumbnail","hentry","topic-strategie-commerciale-investissement","area-canada-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FAQ concernant l&#039;\u00c9nonc\u00e9 des politiques et des proc\u00e9dures de placement (EPPP) - Canada Climate Law Initiative<\/title>\n<meta name=\"description\" content=\"L&#039;\u00e9nonc\u00e9 des politiques et des proc\u00e9dures est un document qui contient des renseignements sur les politiques et proc\u00e9dures de placement concernant le portefeuille de placements et les pr\u00eats d&#039;un r\u00e9gime.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccli.ubc.ca\/fr\/resource\/faqs-statement-of-investment-policies-and-procedures-sipp\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FAQ concernant l&#039;\u00c9nonc\u00e9 des politiques et des proc\u00e9dures de placement (EPPP)\" \/>\n<meta property=\"og:description\" content=\"L&#039;\u00e9nonc\u00e9 des politiques et des proc\u00e9dures est un document qui contient des renseignements sur les politiques et proc\u00e9dures de placement concernant le portefeuille de placements et les pr\u00eats d&#039;un r\u00e9gime.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccli.ubc.ca\/fr\/resource\/faqs-statement-of-investment-policies-and-procedures-sipp\/\" \/>\n<meta property=\"og:site_name\" content=\"Canada Climate Law Initiative\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-02T19:15:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccli.ubc.ca\/wp-content\/uploads\/2021\/04\/Stock-photo_91-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"FAQ concernant l&#039;\u00c9nonc\u00e9 des politiques et des proc\u00e9dures de placement (EPPP)\" \/>\n<meta name=\"twitter:description\" content=\"L&#039;\u00e9nonc\u00e9 des politiques et des proc\u00e9dures est un document qui contient des renseignements sur les politiques et proc\u00e9dures de placement concernant le portefeuille de placements et les pr\u00eats d&#039;un r\u00e9gime.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/ccli.ubc.ca\/wp-content\/uploads\/2021\/04\/Stock-photo_91-scaled.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ccli.ubc.ca\\\/fr\\\/resource\\\/faqs-statement-of-investment-policies-and-procedures-sipp\\\/\",\"url\":\"https:\\\/\\\/ccli.ubc.ca\\\/fr\\\/resource\\\/faqs-statement-of-investment-policies-and-procedures-sipp\\\/\",\"name\":\"FAQ concernant l'\u00c9nonc\u00e9 des politiques et des proc\u00e9dures de placement (EPPP) - Canada Climate Law Initiative\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ccli.ubc.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ccli.ubc.ca\\\/fr\\\/resource\\\/faqs-statement-of-investment-policies-and-procedures-sipp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ccli.ubc.ca\\\/fr\\\/resource\\\/faqs-statement-of-investment-policies-and-procedures-sipp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ccli.ubc.ca\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Stock-photo_91-scaled.jpg\",\"datePublished\":\"2017-10-01T21:02:00+00:00\",\"dateModified\":\"2021-11-02T19:15:17+00:00\",\"description\":\"L'\u00e9nonc\u00e9 des politiques et des proc\u00e9dures est un document qui contient des renseignements sur les politiques et proc\u00e9dures de placement concernant le portefeuille de placements et les pr\u00eats d'un r\u00e9gime.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ccli.ubc.ca\\\/fr\\\/resource\\\/faqs-statement-of-investment-policies-and-procedures-sipp\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ccli.ubc.ca\\\/fr\\\/resource\\\/faqs-statement-of-investment-policies-and-procedures-sipp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/ccli.ubc.ca\\\/fr\\\/resource\\\/faqs-statement-of-investment-policies-and-procedures-sipp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ccli.ubc.ca\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Stock-photo_91-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/ccli.ubc.ca\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Stock-photo_91-scaled.jpg\",\"width\":2560,\"height\":1709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ccli.ubc.ca\\\/fr\\\/resource\\\/faqs-statement-of-investment-policies-and-procedures-sipp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ccli.ubc.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQ concernant l&rsquo;\u00c9nonc\u00e9 des politiques et des proc\u00e9dures de placement (EPPP)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ccli.ubc.ca\\\/#website\",\"url\":\"https:\\\/\\\/ccli.ubc.ca\\\/\",\"name\":\"Canada Climate Law Initiative\",\"description\":\"Understand climate-related risks and opportunities\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ccli.ubc.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FAQ concernant l'\u00c9nonc\u00e9 des politiques et des proc\u00e9dures de placement (EPPP) - Canada Climate Law Initiative","description":"L'\u00e9nonc\u00e9 des politiques et des proc\u00e9dures est un document qui contient des renseignements sur les politiques et proc\u00e9dures de placement concernant le portefeuille de placements et les pr\u00eats d'un r\u00e9gime.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccli.ubc.ca\/fr\/resource\/faqs-statement-of-investment-policies-and-procedures-sipp\/","og_locale":"fr_FR","og_type":"article","og_title":"FAQ concernant l'\u00c9nonc\u00e9 des politiques et des proc\u00e9dures de placement (EPPP)","og_description":"L'\u00e9nonc\u00e9 des politiques et des proc\u00e9dures est un document qui contient des renseignements sur les politiques et proc\u00e9dures de placement concernant le portefeuille de placements et les pr\u00eats d'un r\u00e9gime.","og_url":"https:\/\/ccli.ubc.ca\/fr\/resource\/faqs-statement-of-investment-policies-and-procedures-sipp\/","og_site_name":"Canada Climate Law Initiative","article_modified_time":"2021-11-02T19:15:17+00:00","og_image":[{"width":2560,"height":1709,"url":"https:\/\/ccli.ubc.ca\/wp-content\/uploads\/2021\/04\/Stock-photo_91-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"FAQ concernant l'\u00c9nonc\u00e9 des politiques et des proc\u00e9dures de placement (EPPP)","twitter_description":"L'\u00e9nonc\u00e9 des politiques et des proc\u00e9dures est un document qui contient des renseignements sur les politiques et proc\u00e9dures de placement concernant le portefeuille de placements et les pr\u00eats d'un r\u00e9gime.","twitter_image":"https:\/\/ccli.ubc.ca\/wp-content\/uploads\/2021\/04\/Stock-photo_91-scaled.jpg","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ccli.ubc.ca\/fr\/resource\/faqs-statement-of-investment-policies-and-procedures-sipp\/","url":"https:\/\/ccli.ubc.ca\/fr\/resource\/faqs-statement-of-investment-policies-and-procedures-sipp\/","name":"FAQ concernant l'\u00c9nonc\u00e9 des politiques et des proc\u00e9dures de placement (EPPP) - Canada Climate Law Initiative","isPartOf":{"@id":"https:\/\/ccli.ubc.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccli.ubc.ca\/fr\/resource\/faqs-statement-of-investment-policies-and-procedures-sipp\/#primaryimage"},"image":{"@id":"https:\/\/ccli.ubc.ca\/fr\/resource\/faqs-statement-of-investment-policies-and-procedures-sipp\/#primaryimage"},"thumbnailUrl":"https:\/\/ccli.ubc.ca\/wp-content\/uploads\/2021\/04\/Stock-photo_91-scaled.jpg","datePublished":"2017-10-01T21:02:00+00:00","dateModified":"2021-11-02T19:15:17+00:00","description":"L'\u00e9nonc\u00e9 des politiques et des proc\u00e9dures est un document qui contient des renseignements sur les politiques et proc\u00e9dures de placement concernant le portefeuille de placements et les pr\u00eats d'un r\u00e9gime.","breadcrumb":{"@id":"https:\/\/ccli.ubc.ca\/fr\/resource\/faqs-statement-of-investment-policies-and-procedures-sipp\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccli.ubc.ca\/fr\/resource\/faqs-statement-of-investment-policies-and-procedures-sipp\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/ccli.ubc.ca\/fr\/resource\/faqs-statement-of-investment-policies-and-procedures-sipp\/#primaryimage","url":"https:\/\/ccli.ubc.ca\/wp-content\/uploads\/2021\/04\/Stock-photo_91-scaled.jpg","contentUrl":"https:\/\/ccli.ubc.ca\/wp-content\/uploads\/2021\/04\/Stock-photo_91-scaled.jpg","width":2560,"height":1709},{"@type":"BreadcrumbList","@id":"https:\/\/ccli.ubc.ca\/fr\/resource\/faqs-statement-of-investment-policies-and-procedures-sipp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ccli.ubc.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"FAQ concernant l&rsquo;\u00c9nonc\u00e9 des politiques et des proc\u00e9dures de placement (EPPP)"}]},{"@type":"WebSite","@id":"https:\/\/ccli.ubc.ca\/#website","url":"https:\/\/ccli.ubc.ca\/","name":"Canada Climate Law Initiative","description":"Understand climate-related risks and opportunities","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccli.ubc.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/resource\/4880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/resource"}],"about":[{"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/types\/resource"}],"version-history":[{"count":3,"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/resource\/4880\/revisions"}],"predecessor-version":[{"id":6983,"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/resource\/4880\/revisions\/6983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/media\/2037"}],"wp:attachment":[{"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/media?parent=4880"}],"wp:term":[{"taxonomy":"resource_type","embeddable":true,"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/resource_type?post=4880"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/topic?post=4880"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/ccli.ubc.ca\/fr\/wp-json\/wp\/v2\/area?post=4880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}